{"id":8754,"date":"2016-03-14T14:33:38","date_gmt":"2016-03-14T14:33:38","guid":{"rendered":"http:\/\/brooklyn.fatmoon.kinsta.com\/?page_id=2"},"modified":"2025-04-14T09:27:26","modified_gmt":"2025-04-14T09:27:26","slug":"rent-ebike","status":"publish","type":"page","link":"https:\/\/obala.rent-ebike.si\/it\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"8754\" class=\"elementor elementor-8754\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bcec401 elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"bcec401\" data-element_type=\"section\" id=\"home\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52a7eaf animated-slow elementor-invisible\" data-id=\"52a7eaf\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fb37da elementor-widget elementor-widget-heading\" data-id=\"6fb37da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">SCOPRITE LA BELLEZZA DELLA COSTA SLOVENA CON LA BICICLETTA ELETTRICA<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccac4cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccac4cc\" data-element_type=\"section\" id=\"ponudba\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73fec25f\" data-id=\"73fec25f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-224080a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"224080a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-88b51a7\" data-id=\"88b51a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83e9369 elementor-widget elementor-widget-heading\" data-id=\"83e9369\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Offerta<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-342e3de elementor-widget elementor-widget-text-editor\" data-id=\"342e3de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">Scoprite le bellezze e gli angoli nascosti della costa slovena e percorrete in bicicletta elettrica la bellissima pista ciclabile Parenzana, che un tempo era una linea ferroviaria che partiva da Trieste e raggiungeva Parenzo. Durante il viaggio viziatevi con  in piatti istriani e gustatevi un caff\u00e8 in riva al mare.<\/p><p style=\"text-align: justify;\">La costa slovena \u00e8 il luogo ideale per un viaggio attivo in e-bike con la famiglia e gli amici,  lungo l'intera costa si snoda un percorso naturalistico con diverse attrazioni e bellezze che si possono trovare solo qui da noi.<\/p><p>Con le nuove e comode biciclette elettriche con un'autonomia fino a 80 km, scoprire questi luoghi sar\u00e0 pi\u00f9 facile e divertente, e le salite non saranno un grosso ostacolo. Per mantenere la sicurezza, abbiamo incluso nel prezzo il casco!<\/p><p style=\"text-align: justify;\">Ci trovate a Isola (Trg padlih za svobodo 9, Izola) e a Capodistria (Kampel 103, Koper).<br \/><b>Annunciate la vostra visita chiamando il numero +386 70 736 745.<\/b><\/p><h5 style=\"text-align: center;\"><strong>Perch\u00e9 scegliere la bicicletta elettrica?<\/strong><\/h5><ul><li>perch\u00e9 siamo amanti della natura e della vita all'aria aperta;<\/li><li>perch\u00e9 vogliamo trascorrere il nostro tempo libero in modo attivo;<\/li><li>perch\u00e9 percorriamo pi\u00f9 <strong>velocemente distanze maggiori e non siamo limitati dalle salite<\/strong>;<\/li><li>perch\u00e9 il percorso \u00e8 semplice, pi\u00f9 facile e possiamo affrontare le condizioni di vento;<\/li><li>perch\u00e9 siamo attenti all'ambiente.<\/li><\/ul><h5 style=\"text-align: center;\">Listino prezzi e condizioni di noleggio<\/h5><p>Il costo di noleggio dell' e-bike per l'intera giornata \u00e8 di 45 EUR, per mezza giornata (fino a 5 ore) 30 EUR. Offriamo inoltre sconti per il noleggio di e-bike per pi\u00f9 giorni o per gruppi pi\u00f9 numerosi (oltre 5 persone). Contattateci e vi faremo un'offerta.<\/p><h5 style=\"text-align: center;\">Riccordatevi che<\/h5><ul><li>Il casco da bici \u00e8 incluso nel prezzo della bici elettrica.<\/li><li>Tutte le attrezzature vengono regolarmente revisionate e ispezionate prima della consegna.<\/li><li>\u00c8 possibile consegnare le biciclette su richiesta.<\/li><li>I termini e le condizioni per il noleggio di biciclette elettriche sono disponibili <a href=\"http:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2022\/06\/Pogodba.pdf\" target=\"_blank\" rel=\"noopener\">qui sotto<\/a><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ac608a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ac608a\" data-element_type=\"section\" id=\"galerija\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be6b3b3\" data-id=\"be6b3b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ab58fa elementor-widget elementor-widget-heading\" data-id=\"9ab58fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Galleria<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaed87e elementor-widget elementor-widget-image-gallery\" data-id=\"eaed87e\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-8754 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed87e\" data-elementor-lightbox-title=\"parenzana_13\" href='https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_13.jpeg'><img width=\"300\" height=\"200\" src=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_13-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_13-300x200.jpeg 300w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_13-1024x683.jpeg 1024w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_13-768x512.jpeg 768w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_13-18x12.jpeg 18w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_13.jpeg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed87e\" data-elementor-lightbox-title=\"parenzana-02\" href='https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana-02.jpeg'><img width=\"300\" height=\"200\" src=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana-02-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana-02-300x200.jpeg 300w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana-02-1024x683.jpeg 1024w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana-02-768x512.jpeg 768w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana-02-18x12.jpeg 18w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana-02.jpeg 1300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed87e\" data-elementor-lightbox-title=\"parenzana_06\" href='https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_06.jpeg'><img width=\"300\" height=\"200\" src=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_06-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_06-300x200.jpeg 300w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_06-1024x683.jpeg 1024w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_06-768x512.jpeg 768w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_06-18x12.jpeg 18w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_06.jpeg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed87e\" data-elementor-lightbox-title=\"parenzana_21\" href='https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_21.jpeg'><img width=\"300\" height=\"200\" src=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_21-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_21-300x200.jpeg 300w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_21-1024x683.jpeg 1024w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_21-768x512.jpeg 768w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_21-18x12.jpeg 18w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_21.jpeg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed87e\" data-elementor-lightbox-title=\"parenzana_14\" href='https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_14.jpeg'><img width=\"300\" height=\"200\" src=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_14-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_14-300x200.jpeg 300w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_14-1024x683.jpeg 1024w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_14-768x512.jpeg 768w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_14-18x12.jpeg 18w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_14.jpeg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed87e\" data-elementor-lightbox-title=\"parenzana_32\" href='https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_32.jpeg'><img width=\"300\" height=\"200\" src=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_32-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_32-300x200.jpeg 300w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_32-1024x683.jpeg 1024w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_32-768x512.jpeg 768w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_32-18x12.jpeg 18w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/03\/parenzana_32.jpeg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22c4287 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22c4287\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1dc48a\" data-id=\"f1dc48a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac1d08f elementor-widget elementor-widget-heading\" data-id=\"ac1d08f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Percorso<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a0181 elementor-widget elementor-widget-image-gallery\" data-id=\"57a0181\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-8754 gallery-columns-1 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"57a0181\" data-elementor-lightbox-title=\"ebikes obala 2. stran (1)\" href='https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1.jpg'><img width=\"768\" height=\"1088\" src=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1-768x1088.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1-768x1088.jpg 768w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1-212x300.jpg 212w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1-723x1024.jpg 723w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1-1085x1536.jpg 1085w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1-1446x2048.jpg 1446w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1-8x12.jpg 8w, https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2023\/04\/ebikes-obala-2.-stran-1.jpg 1459w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6b77fd elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6b77fd\" data-element_type=\"section\" id=\"kje-smo\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad44057\" data-id=\"ad44057\" data-element_type=\"column\" id=\"kje-smo\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7eaeb7 elementor-widget elementor-widget-heading\" data-id=\"d7eaeb7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dove ci trovate?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51c3463 elementor-widget elementor-widget-text-editor\" data-id=\"51c3463\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Abbiamo due sedi:<\/p><div><ul><li>Isola, Piazza dei Caduti per la Libert\u00e0 9, 6310.<\/li><li>Capodistria, Kampel 103, 6000.<\/li><\/ul><p style=\"text-align: center;\">Annunciate la vostra visita chiamando il numero +386 70 736 745.<\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b900a47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b900a47\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-849221d\" data-id=\"849221d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-924f415 elementor-widget elementor-widget-google_maps\" data-id=\"924f415\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" src=\"https:\/\/maps.google.com\/maps?q=Trg%20padlih%20za%20svobodo%209%2C%20Izola&amp;t=m&amp;z=18&amp;output=embed&amp;iwloc=near\" title=\"%3$s\" aria-label=\"%3$s\"><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-126a2a5\" data-id=\"126a2a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-beb76d6 elementor-widget elementor-widget-google_maps\" data-id=\"beb76d6\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" src=\"https:\/\/maps.google.com\/maps?q=Kampel%20103%2C%20Koper&amp;t=m&amp;z=18&amp;output=embed&amp;iwloc=near\" title=\"%3$s\" aria-label=\"%3$s\"><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2767ad3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2767ad3\" data-element_type=\"section\" id=\"kontakt\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-118aa7b\" data-id=\"118aa7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97f18e9 elementor-widget elementor-widget-heading\" data-id=\"97f18e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contatto<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fec9446 elementor-widget elementor-widget-text-editor\" data-id=\"fec9446\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\u010ce nas \u017eelite kontaktirati, nas lahko pokli\u010dete na: +386 70 736 745, ali nam pi\u0161ete na <a href=\"mailto:ebike.obala@gmail.com\">ebike.obala@gmail.com<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Spoznajte lepote OBALE Z E-KOLESOM Ponudba Odkrijte lepote in skrite&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/obala.rent-ebike.si\/it\/\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":1,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false,"ngg_post_thumbnail":0},"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Izposoja e-koles v Moravskih Toplicah<\/title>\n<meta name=\"description\" content=\"Izposodite si e-kolo in do\u017eivite Moravske Toplice! Omogo\u010damo ugodno izposojo elektri\u010dnih koles v Moravskih Toplicah po ugodnih cenah.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/obala.rent-ebike.si\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Izposoja e-koles v Moravskih Toplicah\" \/>\n<meta property=\"og:description\" content=\"Izposodite si e-kolo in do\u017eivite Moravske Toplice! Omogo\u010damo ugodno izposojo elektri\u010dnih koles v Moravskih Toplicah po ugodnih cenah.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/obala.rent-ebike.si\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"Rent e-bike Izola in Koper\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T09:27:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/obala.rent-ebike.si\/\",\"url\":\"https:\/\/obala.rent-ebike.si\/\",\"name\":\"Izposoja e-koles v Moravskih Toplicah\",\"isPartOf\":{\"@id\":\"https:\/\/obala.rent-ebike.si\/#website\"},\"datePublished\":\"2016-03-14T14:33:38+00:00\",\"dateModified\":\"2025-04-14T09:27:26+00:00\",\"description\":\"Izposodite si e-kolo in do\u017eivite Moravske Toplice! Omogo\u010damo ugodno izposojo elektri\u010dnih koles v Moravskih Toplicah po ugodnih cenah.\",\"breadcrumb\":{\"@id\":\"https:\/\/obala.rent-ebike.si\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/obala.rent-ebike.si\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/obala.rent-ebike.si\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/obala.rent-ebike.si\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rent e-bike Moravske Toplice, izposoja e-koles Moravske Toplice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/obala.rent-ebike.si\/#website\",\"url\":\"https:\/\/obala.rent-ebike.si\/\",\"name\":\"Rent e-bike Izola in Koper\",\"description\":\"Izposoja e-koles v Izoli in Kopru.\",\"publisher\":{\"@id\":\"https:\/\/obala.rent-ebike.si\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/obala.rent-ebike.si\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/obala.rent-ebike.si\/#organization\",\"name\":\"Rent e-bike Izola in Koper\",\"url\":\"https:\/\/obala.rent-ebike.si\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/obala.rent-ebike.si\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2021\/07\/cropped-Logo_white-2.png\",\"contentUrl\":\"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2021\/07\/cropped-Logo_white-2.png\",\"width\":1214,\"height\":455,\"caption\":\"Rent e-bike Izola in Koper\"},\"image\":{\"@id\":\"https:\/\/obala.rent-ebike.si\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Izposoja e-koles v Moravskih Toplicah","description":"Izposodite si e-kolo in do\u017eivite Moravske Toplice! Omogo\u010damo ugodno izposojo elektri\u010dnih koles v Moravskih Toplicah po ugodnih cenah.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/obala.rent-ebike.si\/it\/","og_locale":"it_IT","og_type":"article","og_title":"Izposoja e-koles v Moravskih Toplicah","og_description":"Izposodite si e-kolo in do\u017eivite Moravske Toplice! Omogo\u010damo ugodno izposojo elektri\u010dnih koles v Moravskih Toplicah po ugodnih cenah.","og_url":"https:\/\/obala.rent-ebike.si\/it\/","og_site_name":"Rent e-bike Izola in Koper","article_modified_time":"2025-04-14T09:27:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/obala.rent-ebike.si\/","url":"https:\/\/obala.rent-ebike.si\/","name":"Izposoja e-koles v Moravskih Toplicah","isPartOf":{"@id":"https:\/\/obala.rent-ebike.si\/#website"},"datePublished":"2016-03-14T14:33:38+00:00","dateModified":"2025-04-14T09:27:26+00:00","description":"Izposodite si e-kolo in do\u017eivite Moravske Toplice! Omogo\u010damo ugodno izposojo elektri\u010dnih koles v Moravskih Toplicah po ugodnih cenah.","breadcrumb":{"@id":"https:\/\/obala.rent-ebike.si\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/obala.rent-ebike.si\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/obala.rent-ebike.si\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/obala.rent-ebike.si\/"},{"@type":"ListItem","position":2,"name":"Rent e-bike Moravske Toplice, izposoja e-koles Moravske Toplice"}]},{"@type":"WebSite","@id":"https:\/\/obala.rent-ebike.si\/#website","url":"https:\/\/obala.rent-ebike.si\/","name":"Rent e-bike Izola in Koper","description":"Izposoja e-koles v Izoli in Kopru.","publisher":{"@id":"https:\/\/obala.rent-ebike.si\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/obala.rent-ebike.si\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/obala.rent-ebike.si\/#organization","name":"Rent e-bike Izola in Koper","url":"https:\/\/obala.rent-ebike.si\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/obala.rent-ebike.si\/#\/schema\/logo\/image\/","url":"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2021\/07\/cropped-Logo_white-2.png","contentUrl":"https:\/\/obala.rent-ebike.si\/wp-content\/uploads\/2021\/07\/cropped-Logo_white-2.png","width":1214,"height":455,"caption":"Rent e-bike Izola in Koper"},"image":{"@id":"https:\/\/obala.rent-ebike.si\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/pages\/8754"}],"collection":[{"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/comments?post=8754"}],"version-history":[{"count":64,"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/pages\/8754\/revisions"}],"predecessor-version":[{"id":12837,"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/pages\/8754\/revisions\/12837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/obala.rent-ebike.si\/it\/wp-json\/wp\/v2\/media?parent=8754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}